{"id":294,"date":"2024-07-03T23:38:50","date_gmt":"2024-07-03T21:38:50","guid":{"rendered":"https:\/\/ita-staging.de\/zes\/landshut\/?page_id=294"},"modified":"2026-01-26T10:26:02","modified_gmt":"2026-01-26T09:26:02","slug":"endokrinologie","status":"publish","type":"page","link":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/","title":{"rendered":"Endokrinologie"},"content":{"rendered":"\r\n    <div  class=\"simple-header-block\">\r\n        <div class=\"layout-s\">\r\n                            <div class=\"title\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/11\/icon-ver-endokrinologie.svg\" alt=\"icon-ver-endokrinologie\"> \r\n                                        <h1>Endokrinologie in Augsburg<\/h1>\r\n                <\/div>\r\n                                        <p class=\"subline\"> Ihre Experten f\u00fcr Hormonst\u00f6rungen<\/p>\r\n                                        <p>Endokrinologie ist die medizinische Fachrichtung, die sich mit den Hormonen und den Dr\u00fcsen besch\u00e4ftigt, die diese produzieren. Hormone steuern viele wichtige Funktionen im K\u00f6rper, wie Wachstum, Stoffwechsel, Fortpflanzung und Stimmung. St\u00f6rungen im Hormonsystem k\u00f6nnen daher weitreichende Auswirkungen auf Ihre Gesundheit haben. Unser Ziel ist es, diese St\u00f6rungen fr\u00fchzeitig zu erkennen und effektiv zu behandeln.<\/p>\r\n                                <\/div>\r\n    <\/div>\r\n\n\n\r\n\r\n  <div  class=\"fachbereiche-block white col-4\">\r\n\r\n<div class=\"fachbereiche\">\r\n      <h3>Unsere spezialisierten Leistungen<\/h3>\r\n  \r\n  <div class=\"items\" x-data=\"{ openItem: null }\">\r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"cursor-pointer\" @click=\"openItem = openItem === 'item-0' ? null : 'item-0'\"> \r\n                              <span class=\"headline\">\r\n                  Schilddr\u00fcse                                      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\" class=\"size-6\" :class=\"{ 'active': openItem === 'item-0' }\">\r\n                      <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m19.5 8.25-7.5 7.5-7.5-7.5\" \/>\r\n                    <\/svg>\r\n                                  <\/span>\r\n                          \r\n                          <\/p>\r\n          <\/div>\r\n                  <div class=\"hidden-items\">\r\n             \r\n              <div x-show=\"openItem === 'item-0'\" class=\"item\">  \r\n                  <p>Die Schilddr\u00fcse ist das wichtigste Stoffwechselorgan des K\u00f6rpers. Wir diagnostizieren und behandeln alle Schilddr\u00fcsenst\u00f6rungen wie Schilddr\u00fcsenknoten Unterfunktion (z.B. Hashimoto-Thyreoiditis), \u00dcberfunktion (z.B. Morbus Basedow), schmerzhafte Entz\u00fcndungen oder Schilddr\u00fcsenkrebs.<\/p>\n    \r\n            <\/div> \r\n                      <\/div> \r\n                                <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/schilddruesenerkrankungen\/\" class=\"btn-secondary\">Zu Schilddr\u00fcsenerkrankungen              <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn next\" title=\"btn next\">\r\n            <\/a>\r\n                <\/div>\r\n            \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"cursor-pointer\" @click=\"openItem = openItem === 'item-1' ? null : 'item-1'\"> \r\n                              <span class=\"headline\">\r\n                  Nebenschilddr\u00fcse                                      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\" class=\"size-6\" :class=\"{ 'active': openItem === 'item-1' }\">\r\n                      <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m19.5 8.25-7.5 7.5-7.5-7.5\" \/>\r\n                    <\/svg>\r\n                                  <\/span>\r\n                          \r\n                          <\/p>\r\n          <\/div>\r\n                  <div class=\"hidden-items\">\r\n             \r\n              <div x-show=\"openItem === 'item-1'\" class=\"item\">  \r\n                  <p>In den Nebenschilddr\u00fcsen (Epithelk\u00f6rperchen) wird das Parathormon gebildet, dieses Hormon ist f\u00fcr die Regulation des Kalzium- und Phosphatsstoffwechsels zust\u00e4ndig. Wir diagnostizierten und behandeln alle St\u00f6rungen der Nebenschilddr\u00fcsen wie z.B. \u00dcber- oder Unterfunktion (Hyper- oder Hypoparathyreoidismus)<\/p>\n    \r\n            <\/div> \r\n                      <\/div> \r\n                          <\/div>\r\n            \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"cursor-pointer\" @click=\"openItem = openItem === 'item-2' ? null : 'item-2'\"> \r\n                              <span class=\"headline\">\r\n                  Hypophyse                                      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\" class=\"size-6\" :class=\"{ 'active': openItem === 'item-2' }\">\r\n                      <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m19.5 8.25-7.5 7.5-7.5-7.5\" \/>\r\n                    <\/svg>\r\n                                  <\/span>\r\n                          \r\n                          <\/p>\r\n          <\/div>\r\n                  <div class=\"hidden-items\">\r\n             \r\n              <div x-show=\"openItem === 'item-2'\" class=\"item\">  \r\n                  <p>Die Hypophyse (Hirnanhangsdr\u00fcse) ist das zentrale Steuerungsorgan der Hormone im K\u00f6rper. Gutartige Hypophysenadenome sind h\u00e4ufig aber in der Regel harmlos, es k\u00f6nnen allerdings vermehrt Hormone produziert werden oder Mangelzust\u00e4nde entstehen, welche zu gravierenden Erkrankungen f\u00fchren k\u00f6nnen. In der Behandlung von Erkrankungen der Hirnanhangsdr\u00fcse ber\u00fccksichtigen wir die komplexen Wechselwirkungen zwischen Hormonregulation und K\u00f6rperfunktionen und bieten ma\u00dfgeschneiderte L\u00f6sungen an<\/p>\n    \r\n            <\/div> \r\n                      <\/div> \r\n                                <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/hypophysenerkrankungen\/\" class=\"btn-secondary\">Zu Hypophysenerkrankungen              <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn next\" title=\"btn next\">\r\n            <\/a>\r\n                <\/div>\r\n            \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"cursor-pointer\" @click=\"openItem = openItem === 'item-3' ? null : 'item-3'\"> \r\n                              <span class=\"headline\">\r\n                  Nebenniere                                      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\" class=\"size-6\" :class=\"{ 'active': openItem === 'item-3' }\">\r\n                      <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m19.5 8.25-7.5 7.5-7.5-7.5\" \/>\r\n                    <\/svg>\r\n                                  <\/span>\r\n                          \r\n                          <\/p>\r\n          <\/div>\r\n                  <div class=\"hidden-items\">\r\n             \r\n              <div x-show=\"openItem === 'item-3'\" class=\"item\">  \r\n                  <p>Die Nebennieren sind kleine Organe welche oberhalb der Nieren liegen, sie bestehen im inneren aus dem Nebennierenmark und im \u00e4u\u00dferen aus der Nebennierenrinde. In der Nebenniere werden lebensnotwendige Stresshormone gebildet, wie z.B. Adrenalin, Noradrenalin und Cortisol, Aldosteron und DHEA. St\u00f6rungen der Nebennierenfunktion k\u00f6nnen zu Blutdruckentgleisungen, Gewichtsschwankungen, Zyklusst\u00f6rungen und Mehrbehaarung f\u00fchren. Auch eine Cortison-Therapie kann zu einer St\u00f6rung der Nebennierenfunktion f\u00fchren. Wir diagnostizierten und behandeln alle St\u00f6rungen der Nebennieren wie z.B. Morbus Addison, Cushing-Syndrom, adrenogenitales Syndrom<\/p>\n    \r\n            <\/div> \r\n                      <\/div> \r\n                                <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/nebennierenerkrankungen\/\" class=\"btn-secondary\">Zu Nebennierenerkrankungen              <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn next\" title=\"btn next\">\r\n            <\/a>\r\n                <\/div>\r\n            \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"cursor-pointer\" @click=\"openItem = openItem === 'item-4' ? null : 'item-4'\"> \r\n                              <span class=\"headline\">\r\n                  Endokrine Hypertonie                                      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\" class=\"size-6\" :class=\"{ 'active': openItem === 'item-4' }\">\r\n                      <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m19.5 8.25-7.5 7.5-7.5-7.5\" \/>\r\n                    <\/svg>\r\n                                  <\/span>\r\n                          \r\n                          <\/p>\r\n          <\/div>\r\n                  <div class=\"hidden-items\">\r\n             \r\n              <div x-show=\"openItem === 'item-4'\" class=\"item\">  \r\n                  <p>Der Bluthochdruck (arterielle Hypertonie) ist eine h\u00e4ufige chronische Erkrankung, in den westlichen Industriel\u00e4ndern bis zu 25 % der Bev\u00f6lkerung leiden an einen Bluthochdruck. Bei nicht ausreichender Blutdruckkontrolle kann eine sekund\u00e4re Hypertonie dahinterstecken, diese kann Folge von Hormonst\u00f6rungen sein z.B.<\/p>\n<p>&#8211; Schilddr\u00fcsenfunktionsst\u00f6rung<br \/>\n&#8211; Hyperparathyreoidismus<br \/>\n&#8211; Akromegalie<br \/>\n&#8211; Ph\u00e4ochromozytom<br \/>\n&#8211; Hyperaldosteronismus<br \/>\n&#8211; Cushing-Syndrom<\/p>\n<p>Durch detaillierte Hormonanalysen k\u00f6nnen solche Hormonst\u00f6rungen identifiziert werden, danach kann eine individuelle Therapie eingeleitet werden<\/p>\n    \r\n            <\/div> \r\n                      <\/div> \r\n                          <\/div>\r\n            \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"cursor-pointer\" @click=\"openItem = openItem === 'item-5' ? null : 'item-5'\"> \r\n                              <span class=\"headline\">\r\n                  gyn\u00e4kologische Endokrinologie                                      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\" class=\"size-6\" :class=\"{ 'active': openItem === 'item-5' }\">\r\n                      <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m19.5 8.25-7.5 7.5-7.5-7.5\" \/>\r\n                    <\/svg>\r\n                                  <\/span>\r\n                          \r\n                          <\/p>\r\n          <\/div>\r\n                  <div class=\"hidden-items\">\r\n             \r\n              <div x-show=\"openItem === 'item-5'\" class=\"item\">  \r\n                  <p>Hormonst\u00f6rungen bei Frauen k\u00f6nnen in jeder Altersgruppe auftreten, besonders bei<\/p>\n<p>&#8211; Zyklusst\u00f6rungen<br \/>\n&#8211; unerf\u00fclltem Kinderwunsch<br \/>\n&#8211; Akne oder Mehrbehaarung<br \/>\n&#8211; Haarausfall<br \/>\n&#8211; Gewichtsschwankungen<\/p>\n<p>kann eine Hormonst\u00f6rung dahinterstecken. Durch ausf\u00fchrliche Anamnese und gezielte Diagnostik k\u00f6nnen solche Hormonst\u00f6rungen (z.B. PCO-Syndrom, Ovarialinsuffizienz) identifiziert und gezielt behandelt werden<\/p>\n    \r\n            <\/div> \r\n                      <\/div> \r\n                          <\/div>\r\n            \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"cursor-pointer\" @click=\"openItem = openItem === 'item-6' ? null : 'item-6'\"> \r\n                              <span class=\"headline\">\r\n                  Testosteronmangel                                      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\" class=\"size-6\" :class=\"{ 'active': openItem === 'item-6' }\">\r\n                      <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m19.5 8.25-7.5 7.5-7.5-7.5\" \/>\r\n                    <\/svg>\r\n                                  <\/span>\r\n                          \r\n                          <\/p>\r\n          <\/div>\r\n                  <div class=\"hidden-items\">\r\n             \r\n              <div x-show=\"openItem === 'item-6'\" class=\"item\">  \r\n                  <p>Hormonst\u00f6rungen bei M\u00e4nnern k\u00f6nnen in jeder Altersgruppe auftreten, besonders bei Libido- oder Potenzst\u00f6rungen, Muskelschwund, Ersch\u00f6pfung kann ein Testosteronmangel vorliegen. Durch detaillierte Hormonanalysen k\u00f6nnen solche Hormonst\u00f6rungen identifiziert werden, danach kann eine individuelle Therapie eingeleitet werden<\/p>\n    \r\n            <\/div> \r\n                      <\/div> \r\n                          <\/div>\r\n            \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"cursor-pointer\" @click=\"openItem = openItem === 'item-7' ? null : 'item-7'\"> \r\n                              <span class=\"headline\">\r\n                  Gyn\u00e4komastie                                      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\" class=\"size-6\" :class=\"{ 'active': openItem === 'item-7' }\">\r\n                      <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m19.5 8.25-7.5 7.5-7.5-7.5\" \/>\r\n                    <\/svg>\r\n                                  <\/span>\r\n                          \r\n                          <\/p>\r\n          <\/div>\r\n                  <div class=\"hidden-items\">\r\n             \r\n              <div x-show=\"openItem === 'item-7'\" class=\"item\">  \r\n                  <p>Gyn\u00e4komastie ist die ein- oder doppelseitige Vergr\u00f6\u00dferung der Milchdr\u00fcse beim Mann. Man unterscheidet zwischen der echten Gyn\u00e4komastie durch Vermehrung des Dr\u00fcsengewebes von der unechten Brustdr\u00fcsenvergr\u00f6\u00dferung durch Fetteinlagerung bei \u00dcbergewicht\/Adipositas. Medikamente und verschiedene Hormonst\u00f6rungen k\u00f6nnen zur echten Gyn\u00e4komastie f\u00fchren. Durch gezielte Diagnostik k\u00f6nnen Hormonst\u00f6rungen identifiziert werden die zur Gyn\u00e4komastie f\u00fchren und entsprechend behandelt werden<\/p>\n    \r\n            <\/div> \r\n                      <\/div> \r\n                          <\/div>\r\n            \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"cursor-pointer\" @click=\"openItem = openItem === 'item-8' ? null : 'item-8'\"> \r\n                              <span class=\"headline\">\r\n                  Geschlechtsinkongruenz                                      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\" stroke-width=\"1.5\" stroke=\"currentColor\" class=\"size-6\" :class=\"{ 'active': openItem === 'item-8' }\">\r\n                      <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m19.5 8.25-7.5 7.5-7.5-7.5\" \/>\r\n                    <\/svg>\r\n                                  <\/span>\r\n                          \r\n                          <\/p>\r\n          <\/div>\r\n                  <div class=\"hidden-items\">\r\n             \r\n              <div x-show=\"openItem === 'item-8'\" class=\"item\">  \r\n                  <p>Die Geschlechtsinkongruenz (Geschlechtsdysphorie, Transsexualit\u00e4t) beschreibt den Zustand der nicht \u00dcbereinstimmung der Geschlechtsidentit\u00e4t einer Person mit dem biologisch zugewiesenen Geschlecht. Nach Diagnosestellung durch einem erfahrenen Psychotherapeuten werden durch unsere endokrinologische Abkl\u00e4rung Hormonst\u00f6rungen ausgeschlossen und es erfolgt eine Risikoevaluation vor ggf. Einleitung einer geschlechtsangleichenden Hormontherapie<\/p>\n    \r\n            <\/div> \r\n                      <\/div> \r\n                          <\/div>\r\n            \r\n      <\/div>\r\n\r\n  <\/div>\r\n\r\n<\/div>\r\n\r\n\n\n\r\n\r\n    <div  class=\"kachel-block leistungen\"> \r\n      <div class=\"layout-s\">\r\n                   <h3>Weitere Behandlungsschwerpunkte<\/h3>\r\n                \r\n\r\n        <div class=\"kacheln \">\r\n                      <div class=\"kachel \">\r\n                              <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/\">\r\n                                                <p class=\"title\">\r\n                    Diabetologie                  <\/p>\r\n                                                                  <img src='https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/07\/icon-finger.svg' alt='' title='icon-finger'>\r\n                                                  <p class=\"btn-secondary\">Mehr erfahren\r\n                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n                  <\/p>\r\n                                              <\/a>\r\n                          <\/div>\r\n                      <div class=\"kachel \">\r\n                              <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/adipositas\/\">\r\n                                                <p class=\"title\">\r\n                    Adipositas  (\u00dcbergewicht)                  <\/p>\r\n                                                                  <img src='https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/07\/icon-ver-adipositas-24.svg' alt='' title='icon-ver-adipositas-24'>\r\n                                                  <p class=\"btn-secondary\">Mehr erfahren\r\n                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n                  <\/p>\r\n                                              <\/a>\r\n                          <\/div>\r\n                      <div class=\"kachel \">\r\n                              <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/osteologie\/\">\r\n                                                <p class=\"title\">\r\n                    Osteologie                  <\/p>\r\n                                                                  <img src='https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/07\/icon-osteoporose_24.svg' alt='' title='icon-osteoporose_24'>\r\n                                                  <p class=\"btn-secondary\">Mehr erfahren\r\n                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n                  <\/p>\r\n                                              <\/a>\r\n                          <\/div>\r\n                      <div class=\"kachel \">\r\n                              <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/praeventionsmedizin\/\">\r\n                                                <p class=\"title\">\r\n                    Pr\u00e4ventionsmedizin                  <\/p>\r\n                                                                  <img src='https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/07\/icon-praeventionsmedizin-24.svg' alt='' title='icon-praeventionsmedizin-24'>\r\n                                                  <p class=\"btn-secondary\">Mehr erfahren\r\n                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n                  <\/p>\r\n                                              <\/a>\r\n                          <\/div>\r\n                      <div class=\"kachel \">\r\n                              <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/ernaehrungsberatung\/\">\r\n                                                <p class=\"title\">\r\n                    Ern\u00e4hrungs- beratung                  <\/p>\r\n                                                                  <img src='https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/07\/icon-ernaehrungsberatung.svg' alt='' title='icon-ernaehrungsberatung'>\r\n                                                  <p class=\"btn-secondary\">Mehr erfahren\r\n                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n                  <\/p>\r\n                                              <\/a>\r\n                          <\/div>\r\n                  <\/div>\r\n\r\n                    <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/\" class=\"btn-primary \">\r\n              Zu der Leistungs\u00fcbersicht              <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next.svg\" alt=\"btn next\" title=\"btn next\">\r\n            <\/a>\r\n              <\/div>\r\n    <\/div>\r\n\r\n\n\n    <div  class=\"accordion-block \">\r\n        <div class=\"layout-s\">\r\n                            <h3>Infopool<\/h3>\r\n            \r\n            <div class=\"accordion\" x-data=\"{ open: null }\">\r\n                                        <div class=\"item\">\r\n                            <button @click=\"open = open === 0 ? null : 0\">\r\n                                Wie lange dauert eine Behandlung?                                <img decoding=\"async\" x-show=\"open !== 0\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_closed.svg\" \r\n                                     alt=\"Closed\" style=\"display: none;\">\r\n                                <img decoding=\"async\" x-show=\"open === 0\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_open.svg\" \r\n                                     alt=\"Open\" style=\"display: none;\">\r\n                            <\/button>\r\n                            <div x-show=\"open === 0\" x-collapse class=\"content\">\r\n                                <p>Die Dauer der Behandlung h\u00e4ngt von der Art und dem Schweregrad der hormonellen St\u00f6rung ab. In der Regel erstrecken sich die Behandlungen \u00fcber mehrere Monate mit regelm\u00e4\u00dfigen Kontrollterminen.<\/p>\n                            <\/div>\r\n                        <\/div>\r\n                                                            <div class=\"item\">\r\n                            <button @click=\"open = open === 1 ? null : 1\">\r\n                                Muss ich eine \u00dcberweisung von meinem Hausarzt haben?                                <img decoding=\"async\" x-show=\"open !== 1\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_closed.svg\" \r\n                                     alt=\"Closed\" style=\"display: none;\">\r\n                                <img decoding=\"async\" x-show=\"open === 1\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_open.svg\" \r\n                                     alt=\"Open\" style=\"display: none;\">\r\n                            <\/button>\r\n                            <div x-show=\"open === 1\" x-collapse class=\"content\">\r\n                                <p>In den meisten F\u00e4llen ist eine \u00dcberweisung von Ihrem Hausarzt erforderlich, um einen Termin bei einem Endokrinologen zu vereinbaren. Kontaktieren Sie uns, um mehr \u00fcber die spezifischen Anforderungen zu erfahren.<\/p>\n                            <\/div>\r\n                        <\/div>\r\n                                                            <div class=\"item\">\r\n                            <button @click=\"open = open === 2 ? null : 2\">\r\n                                Welche Symptome deuten auf hormonelle St\u00f6rungen hin?                                <img decoding=\"async\" x-show=\"open !== 2\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_closed.svg\" \r\n                                     alt=\"Closed\" style=\"display: none;\">\r\n                                <img decoding=\"async\" x-show=\"open === 2\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_open.svg\" \r\n                                     alt=\"Open\" style=\"display: none;\">\r\n                            <\/button>\r\n                            <div x-show=\"open === 2\" x-collapse class=\"content\">\r\n                                <p>Symptome k\u00f6nnen sehr unterschiedlich sein und reichen von M\u00fcdigkeit, Gewichtszunahme oder -abnahme, Haarausfall, Ver\u00e4nderungen im Menstruationszyklus bis hin zu Stimmungsschwankungen und mehr. Eine genaue Diagnose erfordert eine umfassende medizinische Untersuchung.<\/p>\n                            <\/div>\r\n                        <\/div>\r\n                                    \r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":282,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"standort":[],"class_list":["post-294","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZES Augsburg - Endokrinologie<\/title>\n<meta name=\"description\" content=\"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZES Augsburg - Endokrinologie\" \/>\n<meta property=\"og:description\" content=\"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/\" \/>\n<meta property=\"og:site_name\" content=\"ZES Augsburg\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T09:26:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/endokrinologie\\\/\",\"url\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/endokrinologie\\\/\",\"name\":\"ZES Augsburg - Endokrinologie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/#website\"},\"datePublished\":\"2024-07-03T21:38:50+00:00\",\"dateModified\":\"2026-01-26T09:26:02+00:00\",\"description\":\"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/endokrinologie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/endokrinologie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/endokrinologie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leistungen\",\"item\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Endokrinologie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/#website\",\"url\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/\",\"name\":\"Zentrum f\u00fcr Endokrinologie und Stoffwechsel Landshut\",\"description\":\"Hormone im Gleichgewicht\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZES Augsburg - Endokrinologie","description":"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/","og_locale":"de_DE","og_type":"article","og_title":"ZES Augsburg - Endokrinologie","og_description":"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.","og_url":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/","og_site_name":"ZES Augsburg","article_modified_time":"2026-01-26T09:26:02+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/","url":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/","name":"ZES Augsburg - Endokrinologie","isPartOf":{"@id":"https:\/\/endokrinologie.bayern\/augsburg\/#website"},"datePublished":"2024-07-03T21:38:50+00:00","dateModified":"2026-01-26T09:26:02+00:00","description":"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.","breadcrumb":{"@id":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/endokrinologie.bayern\/augsburg\/"},{"@type":"ListItem","position":2,"name":"Leistungen","item":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/"},{"@type":"ListItem","position":3,"name":"Endokrinologie"}]},{"@type":"WebSite","@id":"https:\/\/endokrinologie.bayern\/augsburg\/#website","url":"https:\/\/endokrinologie.bayern\/augsburg\/","name":"Zentrum f\u00fcr Endokrinologie und Stoffwechsel Landshut","description":"Hormone im Gleichgewicht","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/endokrinologie.bayern\/augsburg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/pages\/294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/comments?post=294"}],"version-history":[{"count":11,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/pages\/294\/revisions"}],"predecessor-version":[{"id":826,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/pages\/294\/revisions\/826"}],"up":[{"embeddable":true,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/pages\/282"}],"wp:attachment":[{"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/media?parent=294"}],"wp:term":[{"taxonomy":"standort","embeddable":true,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/standort?post=294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}