{"id":289,"date":"2024-07-03T23:26:13","date_gmt":"2024-07-03T21:26:13","guid":{"rendered":"https:\/\/ita-staging.de\/zes\/landshut\/?page_id=289"},"modified":"2026-01-26T10:25:38","modified_gmt":"2026-01-26T09:25:38","slug":"diabetologie","status":"publish","type":"page","link":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/","title":{"rendered":"Diabetologie"},"content":{"rendered":"\r\n    <div  class=\"simple-header-block\">\r\n        <div class=\"layout-s\">\r\n                            <div class=\"title\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/11\/icon-ver-diabetologie.svg\" alt=\"icon-ver-diabetologie\"> \r\n                                        <h1>Diabetologie in Augsburg<\/h1>\r\n                <\/div>\r\n                                        <p class=\"subline\">Ihr Zentrum f\u00fcr Diabetologie und Stoffwechsel<\/p>\r\n                                        <p>Wir diagnostizieren und behandeln s\u00e4mtliche St\u00f6rungen aus dem Bereich des Glukosestoffwechsels.\r\n\r\nDabei m\u00f6chten wir Ihnen unter Nutzung der stets aktuellsten Therapiem\u00f6glichkeiten zu einem bestm\u00f6glichen und sicheren Umgang mit Ihrer Erkrankung verhelfen, sodass diabetesbedingte Folgeerkrankungen verhindert, bzw. in ihrem Fortschreiten gebremst werden.<\/p>\r\n                                        <a href=\"mailto:info@zes-augsburg.de\" class=\"btn-primary\" target=\"_self\">\r\n                    Zur Terminvereinbarung                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/btn-next.svg\" alt=\"btn next\" title=\"btn next\">\r\n                <\/a>\r\n                    <\/div>\r\n    <\/div>\r\n\n\n\r\n\r\n  <div  class=\"fachbereiche-block white col-4\">\r\n\r\n<div class=\"layout\">\r\n      <h3>Unsere spezialisierten Leistungen<\/h3>\r\n  \r\n  <div class=\"items\" x-data=\"{ openItem: null }\">\r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-0' ? null : 'item-0'\"> \r\n                                                Fr\u00fcherkennung von Glukosestoff-wechselst\u00f6rungen (Pr\u00e4diabetes)                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-1' ? null : 'item-1'\"> \r\n                                                Betreuung Typ-1-Diabetes                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-2' ? null : 'item-2'\"> \r\n                                                Betreuung Typ-2-Diabetes                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-3' ? null : 'item-3'\"> \r\n                                                Diagnostik und Betreuung f\u00fcr Frauen mit Schwangerschaftsdiabetes (Gestationsdiabetes) sowie schwangeren Patientinnen mit Typ-1- oder Typ-2-Diabetes                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-4' ? null : 'item-4'\"> \r\n                                                Diagnostik und Betreuung bei Diabetes-Sonderformen (MODY, pankreopriv, endokrine Ursachen, medikament\u00f6s bedingt)                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-5' ? null : 'item-5'\"> \r\n                                                Intensivierte Insulintherapie                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-6' ? null : 'item-6'\"> \r\n                                                Spezialsprechstunde: Etablierung und Betreuung der Therapie mit Insulinpumpen nach aktuellen technischen Standards mit Closed-Loop und AID-Systemen wie YpsoPump, Omnipod 5 u.a.                                 <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-7' ? null : 'item-7'\"> \r\n                                                Elektronische Auswertung von Blutzuckermessger\u00e4ten                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-8' ? null : 'item-8'\"> \r\n                                                Etablierung diagnostischer rtCGM-Systeme (kontinuierliche Glukosemessung) wie Abbott Freestyle libre oder Dexcom                                 <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-9' ? null : 'item-9'\"> \r\n                                                Behandlung schwerer Insulinresistenz                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-10' ? null : 'item-10'\"> \r\n                                                Abkl\u00e4rung PCO-Syndrom (auch bei unerf\u00fclltem Kinderwunsch)                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-11' ? null : 'item-11'\"> \r\n                                                Abkl\u00e4rung Spontanhypoglyk\u00e4mie (Unterzuckerneigung)                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n          <div class=\"item\"> \r\n          <div class=\"head-elm\">\r\n            <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/icon-check.svg\" alt=\"icon\" title=\"icon\">  \r\n            <p class=\"\" @click=\"openItem = openItem === 'item-12' ? null : 'item-12'\"> \r\n                                                Ern\u00e4hrungs- und Lifestyleberatung                                <\/b>\r\n                                                          \r\n                          <\/p>\r\n          <\/div>\r\n                        <\/div>\r\n                          \r\n      <\/div>\r\n\r\n        <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/team\/\" class=\"btn-secondary\">\r\n        Zu unserem Team        <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n      <\/a>\r\n  <\/div>\r\n\r\n<\/div>\r\n\r\n\n\n  <div  class=\"mfa-block \">\r\n    <div class=\"layout-s\">\r\n        <div class=\"content\">\r\n                      <h3>Bei uns sind Sie<br \/> in besten H\u00e4nden<\/h3>\n                  <\/div>\r\n        <div class=\"mitarbeiter single typ-arzt\">\r\n                  <div class=\"item cta\">\r\n             \r\n\r\n                          <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2025\/11\/dr-anastasia-athanasoulia-kaspar.jpg\" \r\n                alt=\"\" \r\n                title=\"dr-anastasia-athanasoulia-kaspar\">\r\n             \r\n\r\n            <div class=\"name-box\">\r\n                              <div class=\"div\">\r\n                                      <p class=\"name\">Prof. Dr. med. Anasthasia Athanasoulia-Kaspar<\/p>\r\n                                                        <p>F\u00c4 f\u00fcr Innere Medizin, Diabetologin, Ern\u00e4hrungsmedizinerin DAEM\/DGEM, Endokrinologin<\/p>\r\n                                                        <a href=\"mailto:info@zes-augsburg.de\">Zur Terminanfrage<\/a>\r\n                                  <\/div>\r\n                                        <\/div>  \r\n                      <\/div>\r\n        \r\n           \r\n        <\/div>\r\n    <\/div>\r\n  <\/div>\r\n\n\n\r\n\r\n    <div  class=\"kachel-block leistungen\"> \r\n      <div class=\"layout-s\">\r\n                   <h3>Weitere Behandlungsschwerpunkte<\/h3>\r\n                \r\n\r\n        <div class=\"kacheln spalte-3\">\r\n                      <div class=\"kachel \">\r\n                              <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/endokrinologie\/\">\r\n                                                <p class=\"title\">\r\n                    Endokrinologie                  <\/p>\r\n                                                                  <img src='https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/07\/icon-ver-endokrenologie.svg' alt='' title='icon-ver-endokrenologie'>\r\n                                                  <p class=\"btn-secondary\">Mehr erfahren\r\n                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n                  <\/p>\r\n                                              <\/a>\r\n                          <\/div>\r\n                      <div class=\"kachel \">\r\n                              <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/adipositas\/\">\r\n                                                <p class=\"title\">\r\n                    Adipositas  (\u00dcbergewicht)                  <\/p>\r\n                                                                  <img src='https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/07\/icon-ver-adipositas-24.svg' alt='' title='icon-ver-adipositas-24'>\r\n                                                  <p class=\"btn-secondary\">Mehr erfahren\r\n                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n                  <\/p>\r\n                                              <\/a>\r\n                          <\/div>\r\n                      <div class=\"kachel \">\r\n                              <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/osteologie\/\">\r\n                                                <p class=\"title\">\r\n                    Osteologie                  <\/p>\r\n                                                                  <img src='https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/07\/icon-osteoporose_24.svg' alt='' title='icon-osteoporose_24'>\r\n                                                  <p class=\"btn-secondary\">Mehr erfahren\r\n                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n                  <\/p>\r\n                                              <\/a>\r\n                          <\/div>\r\n                      <div class=\"kachel \">\r\n                              <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/praeventionsmedizin\/\">\r\n                                                <p class=\"title\">\r\n                    Pr\u00e4ventionsmedizin                  <\/p>\r\n                                                                  <img src='https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/07\/icon-praeventionsmedizin-24.svg' alt='' title='icon-praeventionsmedizin-24'>\r\n                                                  <p class=\"btn-secondary\">Mehr erfahren\r\n                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n                  <\/p>\r\n                                              <\/a>\r\n                          <\/div>\r\n                      <div class=\"kachel \">\r\n                              <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/ernaehrungsberatung\/\">\r\n                                                <p class=\"title\">\r\n                    Ern\u00e4hrungs- beratung                  <\/p>\r\n                                                                  <img src='https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/uploads\/sites\/10\/2024\/07\/icon-ernaehrungsberatung.svg' alt='' title='icon-ernaehrungsberatung'>\r\n                                                  <p class=\"btn-secondary\">Mehr erfahren\r\n                    <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next-black.svg\" alt=\"btn-next\" title=\"btn-next\">\r\n                  <\/p>\r\n                                              <\/a>\r\n                          <\/div>\r\n                  <\/div>\r\n\r\n                    <a href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/\" class=\"btn-primary spalte-3\">\r\n              Zu der Leistungs\u00fcbersicht              <img decoding=\"async\" src=\"https:\/\/endokrinologie.bayern\/wp-content\/themes\/zes_theme\/images\/btn-next.svg\" alt=\"btn next\" title=\"btn next\">\r\n            <\/a>\r\n              <\/div>\r\n    <\/div>\r\n\r\n\n\n    <div  class=\"accordion-block \">\r\n        <div class=\"layout-s\">\r\n                            <h3>Infopool<\/h3>\r\n            \r\n            <div class=\"accordion\" x-data=\"{ open: null }\">\r\n                                        <div class=\"item\">\r\n                            <button @click=\"open = open === 0 ? null : 0\">\r\n                                Wie oft sollte ich zur Kontrolle kommen?                                <img decoding=\"async\" x-show=\"open !== 0\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_closed.svg\" \r\n                                     alt=\"Closed\" style=\"display: none;\">\r\n                                <img decoding=\"async\" x-show=\"open === 0\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_open.svg\" \r\n                                     alt=\"Open\" style=\"display: none;\">\r\n                            <\/button>\r\n                            <div x-show=\"open === 0\" x-collapse class=\"content\">\r\n                                <p>Die H\u00e4ufigkeit der Kontrollen h\u00e4ngt von Ihrem individuellen Behandlungsplan ab. In der Regel empfehlen wir jedoch regelm\u00e4\u00dfige Check-ups alle drei bis sechs Monate, um Ihre Gesundheit und den Fortschritt Ihrer Behandlung zu \u00fcberwachen.<\/p>\n<h4><\/h4>\n                            <\/div>\r\n                        <\/div>\r\n                                                            <div class=\"item\">\r\n                            <button @click=\"open = open === 1 ? null : 1\">\r\n                                Kann ich an den Schulungen und Workshops auch online teilnehmen?                                <img decoding=\"async\" x-show=\"open !== 1\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_closed.svg\" \r\n                                     alt=\"Closed\" style=\"display: none;\">\r\n                                <img decoding=\"async\" x-show=\"open === 1\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_open.svg\" \r\n                                     alt=\"Open\" style=\"display: none;\">\r\n                            <\/button>\r\n                            <div x-show=\"open === 1\" x-collapse class=\"content\">\r\n                                <p>Ja, wir bieten auch Online-Schulungen und Workshops an, sodass Sie flexibel von zu Hause aus teilnehmen k\u00f6nnen. Dies ist besonders hilfreich, wenn Sie einen vollen Terminkalender haben oder weiter entfernt wohnen.<\/p>\n<h4><\/h4>\n                            <\/div>\r\n                        <\/div>\r\n                                                            <div class=\"item\">\r\n                            <button @click=\"open = open === 2 ? null : 2\">\r\n                                Welche Rolle spielt die Familie in der Diabetesbehandlung?                                <img decoding=\"async\" x-show=\"open !== 2\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_closed.svg\" \r\n                                     alt=\"Closed\" style=\"display: none;\">\r\n                                <img decoding=\"async\" x-show=\"open === 2\" \r\n                                     src=\"https:\/\/endokrinologie.bayern\/augsburg\/wp-content\/themes\/zes_theme\/images\/acc_open.svg\" \r\n                                     alt=\"Open\" style=\"display: none;\">\r\n                            <\/button>\r\n                            <div x-show=\"open === 2\" x-collapse class=\"content\">\r\n                                <p>Die Unterst\u00fctzung durch die Familie ist ein wichtiger Bestandteil der Diabetesbehandlung. Wir ermutigen Ihre Angeh\u00f6rigen, an Schulungen und Beratungen teilzunehmen, um ein besseres Verst\u00e4ndnis f\u00fcr Ihre Erkrankung zu entwickeln und Ihnen bestm\u00f6glich zur Seite zu stehen.<\/p>\n<h3><\/h3>\n                            <\/div>\r\n                        <\/div>\r\n                                    \r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":282,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"standort":[],"class_list":["post-289","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZES Augsburg - Diabetologie<\/title>\n<meta name=\"description\" content=\"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZES Augsburg - Diabetologie\" \/>\n<meta property=\"og:description\" content=\"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/\" \/>\n<meta property=\"og:site_name\" content=\"ZES Augsburg\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T09:25:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/diabetologie\\\/\",\"url\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/diabetologie\\\/\",\"name\":\"ZES Augsburg - Diabetologie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/#website\"},\"datePublished\":\"2024-07-03T21:26:13+00:00\",\"dateModified\":\"2026-01-26T09:25:38+00:00\",\"description\":\"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/diabetologie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/diabetologie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/diabetologie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leistungen\",\"item\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/leistungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diabetologie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/#website\",\"url\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/\",\"name\":\"Zentrum f\u00fcr Endokrinologie und Stoffwechsel Landshut\",\"description\":\"Hormone im Gleichgewicht\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/endokrinologie.bayern\\\/augsburg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZES Augsburg - Diabetologie","description":"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/","og_locale":"de_DE","og_type":"article","og_title":"ZES Augsburg - Diabetologie","og_description":"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.","og_url":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/","og_site_name":"ZES Augsburg","article_modified_time":"2026-01-26T09:25:38+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/","url":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/","name":"ZES Augsburg - Diabetologie","isPartOf":{"@id":"https:\/\/endokrinologie.bayern\/augsburg\/#website"},"datePublished":"2024-07-03T21:26:13+00:00","dateModified":"2026-01-26T09:25:38+00:00","description":"Ihr Spezialist in Augsburg f\u00fcr hormonelle und stoffwechselbedingte Erkrankungen. Mit moderner Diagnostik und individuellen Therapien f\u00fcr Ihre Gesundheit.","breadcrumb":{"@id":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/diabetologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/endokrinologie.bayern\/augsburg\/"},{"@type":"ListItem","position":2,"name":"Leistungen","item":"https:\/\/endokrinologie.bayern\/augsburg\/leistungen\/"},{"@type":"ListItem","position":3,"name":"Diabetologie"}]},{"@type":"WebSite","@id":"https:\/\/endokrinologie.bayern\/augsburg\/#website","url":"https:\/\/endokrinologie.bayern\/augsburg\/","name":"Zentrum f\u00fcr Endokrinologie und Stoffwechsel Landshut","description":"Hormone im Gleichgewicht","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/endokrinologie.bayern\/augsburg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/pages\/289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/comments?post=289"}],"version-history":[{"count":16,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/pages\/289\/revisions"}],"predecessor-version":[{"id":876,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/pages\/289\/revisions\/876"}],"up":[{"embeddable":true,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/pages\/282"}],"wp:attachment":[{"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/media?parent=289"}],"wp:term":[{"taxonomy":"standort","embeddable":true,"href":"https:\/\/endokrinologie.bayern\/augsburg\/wp-json\/wp\/v2\/standort?post=289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}